{"id":7,"count":20,"description":"","link":"https:\/\/www.kobe-c.ac.jp\/gender-inst\/category\/event","name":"\u30a4\u30d9\u30f3\u30c8","slug":"event","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kobe-c.ac.jp\/gender-inst\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kobe-c.ac.jp\/gender-inst\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.kobe-c.ac.jp\/gender-inst\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.kobe-c.ac.jp\/gender-inst\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}